{"id":9760,"date":"2025-08-11T13:15:46","date_gmt":"2025-08-11T13:15:46","guid":{"rendered":"https:\/\/apac.lenovodatastoragecentral.com\/?p=20580"},"modified":"2025-08-29T11:11:58","modified_gmt":"2025-08-29T11:11:58","slug":"episode-2-safeguard-your-san-in-15-minutes","status":"publish","type":"post","link":"https:\/\/apac.lenovodatastoragecentral.com\/in\/webinars\/episode-2-safeguard-your-san-in-15-minutes\/","title":{"rendered":"Episode 2: Safeguard your SAN in 15 minutes"},"content":{"rendered":"<h2>What\u2019s inside?<\/h2>\n<p>A discussion on how to get the highest level of security with a 10-minute Q&amp;A, covering:<\/p>\n<ul>\n<li style=\"color: #e42022;\"><span style=\"color: #000;\">Why outdated SANs are a cybersecurity risk<\/span><\/li>\n<li style=\"color: #e42022;\"><span style=\"color: #000;\">Brocade&#8217;s built-in security features that stop attacks before they happen<\/span><\/li>\n<li style=\"color: #e42022;\"><span style=\"color: #000;\">How Lenovo storage + Brocade SAN creates an unbreakable data fortress.<\/span><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>What\u2019s inside? A discussion on how to get the highest level of security with a 10-minute Q&amp;A, covering: Why outdated SANs are a cybersecurity risk Brocade&#8217;s built-in security features that stop attacks before they happen How Lenovo storage + Brocade SAN creates an unbreakable data fortress.<\/p>\n","protected":false},"author":4,"featured_media":9762,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[75,7],"tags":[],"class_list":["post-9760","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-storage-network-modernisation-series","category-webinars"],"acf":[],"_links":{"self":[{"href":"https:\/\/apac.lenovodatastoragecentral.com\/in\/wp-json\/wp\/v2\/posts\/9760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/apac.lenovodatastoragecentral.com\/in\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/apac.lenovodatastoragecentral.com\/in\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/apac.lenovodatastoragecentral.com\/in\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/apac.lenovodatastoragecentral.com\/in\/wp-json\/wp\/v2\/comments?post=9760"}],"version-history":[{"count":2,"href":"https:\/\/apac.lenovodatastoragecentral.com\/in\/wp-json\/wp\/v2\/posts\/9760\/revisions"}],"predecessor-version":[{"id":9771,"href":"https:\/\/apac.lenovodatastoragecentral.com\/in\/wp-json\/wp\/v2\/posts\/9760\/revisions\/9771"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/apac.lenovodatastoragecentral.com\/in\/wp-json\/wp\/v2\/media\/9762"}],"wp:attachment":[{"href":"https:\/\/apac.lenovodatastoragecentral.com\/in\/wp-json\/wp\/v2\/media?parent=9760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/apac.lenovodatastoragecentral.com\/in\/wp-json\/wp\/v2\/categories?post=9760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/apac.lenovodatastoragecentral.com\/in\/wp-json\/wp\/v2\/tags?post=9760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}